{"id":45200,"date":"2016-10-03T10:30:40","date_gmt":"2016-10-03T08:30:40","guid":{"rendered":"https:\/\/rentaload.com\/2016\/10\/03\/test-di-potenza-erp\/"},"modified":"2023-03-10T17:00:48","modified_gmt":"2023-03-10T16:00:48","slug":"test-di-potenza-erp","status":"publish","type":"post","link":"https:\/\/rentaload.com\/it\/2016\/10\/03\/test-di-potenza-erp\/","title":{"rendered":"Test dei generatori in ERP e ospedali"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><p>Gli ospedali e tutti gli ERP devono essere in grado di mantenere l&#8217;alimentazione delle apparecchiature &#8220;di sicurezza&#8221; in caso di interruzione di corrente o di taglio della rete elettrica (circolare DHOS\/E4 2008-114 per i centri sanitari).<\/p>\n<p>A tal fine, l&#8217;ERP e pi\u00f9 in particolare i centri sanitari pubblici e privati ricorrono a prove dei loro generatori di emergenza, da un lato con prove interne attraverso il collegamento degli ascensori o di altri dispositivi direttamente ai generatori, che comporta rischi sia per il personale che per le attrezzature (tagli all&#8217;avvio e all&#8217;arresto).<\/p>\n<p>D&#8217;altra parte, i test possono essere eseguiti tramite un banco di carico che corrisponde alla potenza necessaria per l&#8217;apparecchiatura di sicurezza e\/o il generatore e consente di farlo in modo sicuro.<\/p>\n<p>Per soddisfare questa domanda, Rentaload ha sviluppato una soluzione di noleggio per banchi di carica fino a 6MW.<\/p>\n<p>Queste banche di carico, come tutti i prodotti Rentaload, sono disponibili in 48 ore in Francia e in pochi giorni in Europa e nel mondo.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1665],"tags":[],"class_list":["post-45200","post","type-post","status-publish","format-standard","hentry","category-non-classificato-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RENTALOAD : Test dei generatori in ERP e ospedali -<\/title>\n<meta name=\"description\" content=\"l&#039;uso di banchi di carico per testare i generatori nelle strutture sanitarie e negli ERP \u00e8 essenziale per la sicurezza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rentaload.com\/it\/2016\/10\/03\/test-di-potenza-erp\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RENTALOAD : Test dei generatori in ERP e ospedali -\" \/>\n<meta property=\"og:description\" content=\"l&#039;uso di banchi di carico per testare i generatori nelle strutture sanitarie e negli ERP \u00e8 essenziale per la sicurezza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rentaload.com\/it\/2016\/10\/03\/test-di-potenza-erp\/\" \/>\n<meta property=\"og:site_name\" content=\"Rentaload\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-03T08:30:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-10T16:00:48+00:00\" \/>\n<meta name=\"author\" content=\"Contact Rentaload\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Contact Rentaload\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rentaload.com\\\/it\\\/2016\\\/10\\\/03\\\/test-di-potenza-erp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rentaload.com\\\/it\\\/2016\\\/10\\\/03\\\/test-di-potenza-erp\\\/\"},\"author\":{\"name\":\"Contact Rentaload\",\"@id\":\"https:\\\/\\\/rentaload.com\\\/it\\\/#\\\/schema\\\/person\\\/5123ccfb4f8b4596a194765583e0a435\"},\"headline\":\"Test dei generatori in ERP e ospedali\",\"datePublished\":\"2016-10-03T08:30:40+00:00\",\"dateModified\":\"2023-03-10T16:00:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rentaload.com\\\/it\\\/2016\\\/10\\\/03\\\/test-di-potenza-erp\\\/\"},\"wordCount\":338,\"publisher\":{\"@id\":\"https:\\\/\\\/rentaload.com\\\/it\\\/#organization\"},\"articleSection\":[\"Non classificato\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rentaload.com\\\/it\\\/2016\\\/10\\\/03\\\/test-di-potenza-erp\\\/\",\"url\":\"https:\\\/\\\/rentaload.com\\\/it\\\/2016\\\/10\\\/03\\\/test-di-potenza-erp\\\/\",\"name\":\"RENTALOAD : Test dei generatori in ERP e ospedali -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rentaload.com\\\/it\\\/#website\"},\"datePublished\":\"2016-10-03T08:30:40+00:00\",\"dateModified\":\"2023-03-10T16:00:48+00:00\",\"description\":\"l'uso di banchi di carico per testare i generatori nelle strutture sanitarie e negli ERP \u00e8 essenziale per la sicurezza\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rentaload.com\\\/it\\\/2016\\\/10\\\/03\\\/test-di-potenza-erp\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rentaload.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/rentaload.com\\\/it\\\/\",\"name\":\"Rentaload\",\"description\":\"Load bank hire - location banc de charge - Lastbank vermietung\",\"publisher\":{\"@id\":\"https:\\\/\\\/rentaload.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rentaload.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rentaload.com\\\/it\\\/#organization\",\"name\":\"Rentaload\",\"url\":\"https:\\\/\\\/rentaload.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/rentaload.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rentaload.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/rentaload-logo-location-banc-de-charge-test-louer-1.png\",\"contentUrl\":\"https:\\\/\\\/rentaload.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/rentaload-logo-location-banc-de-charge-test-louer-1.png\",\"width\":470,\"height\":100,\"caption\":\"Rentaload\"},\"image\":{\"@id\":\"https:\\\/\\\/rentaload.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rentaload.com\\\/it\\\/#\\\/schema\\\/person\\\/5123ccfb4f8b4596a194765583e0a435\",\"name\":\"Contact Rentaload\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7f81a789400b9b2e0a20055f8f15e67de93ebf51d3981b0d248ba8ba66483d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7f81a789400b9b2e0a20055f8f15e67de93ebf51d3981b0d248ba8ba66483d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7f81a789400b9b2e0a20055f8f15e67de93ebf51d3981b0d248ba8ba66483d2?s=96&d=mm&r=g\",\"caption\":\"Contact Rentaload\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RENTALOAD : Test dei generatori in ERP e ospedali -","description":"l'uso di banchi di carico per testare i generatori nelle strutture sanitarie e negli ERP \u00e8 essenziale per la sicurezza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rentaload.com\/it\/2016\/10\/03\/test-di-potenza-erp\/","og_locale":"it_IT","og_type":"article","og_title":"RENTALOAD : Test dei generatori in ERP e ospedali -","og_description":"l'uso di banchi di carico per testare i generatori nelle strutture sanitarie e negli ERP \u00e8 essenziale per la sicurezza","og_url":"https:\/\/rentaload.com\/it\/2016\/10\/03\/test-di-potenza-erp\/","og_site_name":"Rentaload","article_published_time":"2016-10-03T08:30:40+00:00","article_modified_time":"2023-03-10T16:00:48+00:00","author":"Contact Rentaload","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Contact Rentaload","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rentaload.com\/it\/2016\/10\/03\/test-di-potenza-erp\/#article","isPartOf":{"@id":"https:\/\/rentaload.com\/it\/2016\/10\/03\/test-di-potenza-erp\/"},"author":{"name":"Contact Rentaload","@id":"https:\/\/rentaload.com\/it\/#\/schema\/person\/5123ccfb4f8b4596a194765583e0a435"},"headline":"Test dei generatori in ERP e ospedali","datePublished":"2016-10-03T08:30:40+00:00","dateModified":"2023-03-10T16:00:48+00:00","mainEntityOfPage":{"@id":"https:\/\/rentaload.com\/it\/2016\/10\/03\/test-di-potenza-erp\/"},"wordCount":338,"publisher":{"@id":"https:\/\/rentaload.com\/it\/#organization"},"articleSection":["Non classificato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/rentaload.com\/it\/2016\/10\/03\/test-di-potenza-erp\/","url":"https:\/\/rentaload.com\/it\/2016\/10\/03\/test-di-potenza-erp\/","name":"RENTALOAD : Test dei generatori in ERP e ospedali -","isPartOf":{"@id":"https:\/\/rentaload.com\/it\/#website"},"datePublished":"2016-10-03T08:30:40+00:00","dateModified":"2023-03-10T16:00:48+00:00","description":"l'uso di banchi di carico per testare i generatori nelle strutture sanitarie e negli ERP \u00e8 essenziale per la sicurezza","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rentaload.com\/it\/2016\/10\/03\/test-di-potenza-erp\/"]}]},{"@type":"WebSite","@id":"https:\/\/rentaload.com\/it\/#website","url":"https:\/\/rentaload.com\/it\/","name":"Rentaload","description":"Load bank hire - location banc de charge - Lastbank vermietung","publisher":{"@id":"https:\/\/rentaload.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rentaload.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/rentaload.com\/it\/#organization","name":"Rentaload","url":"https:\/\/rentaload.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/rentaload.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/rentaload.com\/wp-content\/uploads\/2018\/03\/rentaload-logo-location-banc-de-charge-test-louer-1.png","contentUrl":"https:\/\/rentaload.com\/wp-content\/uploads\/2018\/03\/rentaload-logo-location-banc-de-charge-test-louer-1.png","width":470,"height":100,"caption":"Rentaload"},"image":{"@id":"https:\/\/rentaload.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rentaload.com\/it\/#\/schema\/person\/5123ccfb4f8b4596a194765583e0a435","name":"Contact Rentaload","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e7f81a789400b9b2e0a20055f8f15e67de93ebf51d3981b0d248ba8ba66483d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e7f81a789400b9b2e0a20055f8f15e67de93ebf51d3981b0d248ba8ba66483d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e7f81a789400b9b2e0a20055f8f15e67de93ebf51d3981b0d248ba8ba66483d2?s=96&d=mm&r=g","caption":"Contact Rentaload"}}]}},"_links":{"self":[{"href":"https:\/\/rentaload.com\/it\/wp-json\/wp\/v2\/posts\/45200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaload.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rentaload.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rentaload.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/rentaload.com\/it\/wp-json\/wp\/v2\/comments?post=45200"}],"version-history":[{"count":2,"href":"https:\/\/rentaload.com\/it\/wp-json\/wp\/v2\/posts\/45200\/revisions"}],"predecessor-version":[{"id":45205,"href":"https:\/\/rentaload.com\/it\/wp-json\/wp\/v2\/posts\/45200\/revisions\/45205"}],"wp:attachment":[{"href":"https:\/\/rentaload.com\/it\/wp-json\/wp\/v2\/media?parent=45200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rentaload.com\/it\/wp-json\/wp\/v2\/categories?post=45200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rentaload.com\/it\/wp-json\/wp\/v2\/tags?post=45200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}